{"id":3012,"date":"2021-02-12T13:34:02","date_gmt":"2021-02-12T13:34:02","guid":{"rendered":"https:\/\/www.anteaprevencion.com\/sedes\/antea-las-rozas-de-madrid\/"},"modified":"2022-04-21T12:50:35","modified_gmt":"2022-04-21T12:50:35","slug":"antea-las-rozas-de-madrid","status":"publish","type":"sedes","link":"https:\/\/www.anteaprevencion.com\/cat\/sedes\/antea-las-rozas-de-madrid\/","title":{"rendered":"Delegaci\u00f3 de Las Rozas"},"content":{"rendered":"<h5>Servicios Antea&nbsp;Las Rozas<\/h5>\n<ul class=\"servicios-sedes\">\n<li>Prevenci\u00f3 Riscos Laborals<\/li>\n<li>Vigil\u00e0ncia de la Salut<\/li>\n<li>Pla unico PRL<\/li>\n<li>Prevenci\u00f3 Aut\u00f2noms<\/li>\n<li>Serveis Especialitzats<\/li>\n<li>Formaci\u00f3<\/li>\n<li>Reconeixements M\u00e8dics<\/li>\n<\/ul>","protected":false},"featured_media":4948,"template":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Delegaci\u00f3n de Las Rozas - Prevenci\u00f3n de Riesgos Laborales | PRL | Antea Prevenci\u00f3n<\/title>\r\n<meta name=\"description\" content=\"{:es} Antea Las Rozas Prevenci\u00f3n Riesgos Laborales{:ca}C\/ Londres, 38 - Bajo 8 (28232) - Las Rozas de Madrid. 954 181 445{:}\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.anteaprevencion.com\/cat\/sedes\/antea-las-rozas-de-madrid\/\" \/>\r\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Delegaci\u00f3n de Las Rozas - Prevenci\u00f3n de Riesgos Laborales | PRL | Antea Prevenci\u00f3n\" \/>\r\n<meta property=\"og:description\" content=\"{:es} Antea Las Rozas Prevenci\u00f3n Riesgos Laborales{:ca}C\/ Londres, 38 - Bajo 8 (28232) - Las Rozas de Madrid. 954 181 445{:}\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.anteaprevencion.com\/cat\/sedes\/antea-las-rozas-de-madrid\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Prevenci\u00f3n de Riesgos Laborales | PRL | Antea Prevenci\u00f3n\" \/>\r\n<meta property=\"article:modified_time\" content=\"2022-04-21T12:50:35+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.anteaprevencion.com\/wp-content\/uploads\/2021\/02\/lasrozas-web.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"751\" \/>\r\n\t<meta property=\"og:image:height\" content=\"504\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\">\n\t<meta name=\"twitter:data1\" content=\"1 minut\">\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.anteaprevencion.com\/#website\",\"url\":\"https:\/\/www.anteaprevencion.com\/\",\"name\":\"Prevenci\\u00f3n de Riesgos Laborales | PRL | Antea Prevenci\\u00f3n\",\"description\":\"Somos empresa l\\u00edder de prevenci\\u00f3n de riesgos laborales para tu negocio. Servicio de PRL, vigilancia de la salud, reconocimientos m\\u00e9dicos.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.anteaprevencion.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.anteaprevencion.com\/sedes\/antea-las-rozas-de-madrid\/#primaryimage\",\"inLanguage\":\"ca\",\"url\":\"https:\/\/www.anteaprevencion.com\/wp-content\/uploads\/2021\/02\/lasrozas-web.png\",\"width\":751,\"height\":504},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.anteaprevencion.com\/sedes\/antea-las-rozas-de-madrid\/#webpage\",\"url\":\"https:\/\/www.anteaprevencion.com\/sedes\/antea-las-rozas-de-madrid\/\",\"name\":\"Delegaci\\u00f3n de Las Rozas - Prevenci\\u00f3n de Riesgos Laborales | PRL | Antea Prevenci\\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.anteaprevencion.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.anteaprevencion.com\/sedes\/antea-las-rozas-de-madrid\/#primaryimage\"},\"datePublished\":\"2021-02-12T13:34:02+00:00\",\"dateModified\":\"2022-04-21T12:50:35+00:00\",\"description\":\"{:es} Antea Las Rozas Prevenci\\u00f3n Riesgos Laborales{:ca}C\/ Londres, 38 - Bajo 8 (28232) - Las Rozas de Madrid. 954 181 445{:}\",\"breadcrumb\":{\"@id\":\"https:\/\/www.anteaprevencion.com\/sedes\/antea-las-rozas-de-madrid\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.anteaprevencion.com\/sedes\/antea-las-rozas-de-madrid\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.anteaprevencion.com\/sedes\/antea-las-rozas-de-madrid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.anteaprevencion.com\/\",\"url\":\"https:\/\/www.anteaprevencion.com\/\",\"name\":\"Portada\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.anteaprevencion.com\/sedes\/\",\"url\":\"https:\/\/www.anteaprevencion.com\/sedes\/\",\"name\":\"Sedes\"}},{\"@type\":\"ListItem\",\"position\":3,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.anteaprevencion.com\/sedes\/antea-las-rozas-de-madrid\/\",\"url\":\"https:\/\/www.anteaprevencion.com\/sedes\/antea-las-rozas-de-madrid\/\",\"name\":\"Delegaci\\u00f3n de Las Rozas\"}}]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.anteaprevencion.com\/cat\/wp-json\/wp\/v2\/sedes\/3012"}],"collection":[{"href":"https:\/\/www.anteaprevencion.com\/cat\/wp-json\/wp\/v2\/sedes"}],"about":[{"href":"https:\/\/www.anteaprevencion.com\/cat\/wp-json\/wp\/v2\/types\/sedes"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.anteaprevencion.com\/cat\/wp-json\/wp\/v2\/media\/4948"}],"wp:attachment":[{"href":"https:\/\/www.anteaprevencion.com\/cat\/wp-json\/wp\/v2\/media?parent=3012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}